{"id":2415,"date":"2025-02-26T19:24:52","date_gmt":"2025-02-26T18:24:52","guid":{"rendered":"https:\/\/prembyg.dk\/?page_id=2415"},"modified":"2025-03-07T13:59:31","modified_gmt":"2025-03-07T12:59:31","slug":"tilretning-af-skabe","status":"publish","type":"page","link":"https:\/\/prembyg.dk\/index.php\/tilretning-af-skabe\/","title":{"rendered":"Tilretning af skabe"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-b5d35cd4 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-90747899\"><h1 class=\"uagb-heading-text\">Tilretning af skabe &#8211; <strong><strong>giv dine eksisterende skabe nyt liv<\/strong><\/strong><\/h1><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-47f641d6 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-25ac16a2 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title-prefix\">Vi er eksperter i tilretning af skabe<\/h6><h2 class=\"uagb-ifb-title\">Passer skabet ikke? Vi tilretter og optimerer dine skabe til dit behov<\/h2><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ed2c2e06 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-5b23f554\">\n<div class=\"wp-block-uagb-info-box uagb-block-4d1b1cd4 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/prembyg.dk\/wp-content\/uploads\/2023\/11\/CF87D5D7-8643-4684-9F6A-7E71E631257E-1-1170x536.jpg\" alt=\"\" width=\"1170\" height=\"536\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\"><strong><strong><strong>Maksimal Udnyttelse af Pladsen \u2013 Optimer Dine Skabe<\/strong><\/strong><\/strong><\/h4><\/div><p class=\"uagb-ifb-desc\">N\u00e5r dine skabe ikke passer perfekt til rummet, g\u00e5r v\u00e6rdifuld plads ofte til spilde. Med professionel tilretning sikrer vi, at dine skabe udnytter hver eneste centimeter optimalt \u2013 selv i rum med sk\u00e6ve vinkler, skr\u00e5 lofter eller begr\u00e6nset plads. Ved at justere, tilpasse og optimere skabsindretningen f\u00e5r du en mere funktionel og str\u00f8mlinet l\u00f8sning, der giver bedre opbevaring og et ryddeligt hjem.<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-fe0a0c96\">\n<div class=\"wp-block-uagb-info-box uagb-block-01f03b24 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/prembyg.dk\/wp-content\/uploads\/2025\/02\/PREMBYG-CBDK05-1170x536.jpg\" alt=\"\" width=\"1170\" height=\"536\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\"><strong><strong>\u00d8konomisk og Stilfuld Opgradering af Dine Skabe<\/strong><\/strong><\/h4><\/div><p class=\"uagb-ifb-desc\">At tilrette eksisterende skabe er en langt mere \u00f8konomisk l\u00f8sning end at investere i helt nye m\u00f8bler. I stedet for en dyr udskiftning kan vi justere l\u00e5ger, h\u00e6ngsler og indretning, s\u00e5 skabet fremst\u00e5r som nyt og matcher din stil. Uanset om du \u00f8nsker et moderne look, klassisk elegance eller en praktisk opgradering, kan vi give dine skabe et l\u00f8ft uden at spr\u00e6nge budgettet.<br><br><br><\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-fa91d8ee\">\n<div class=\"wp-block-uagb-info-box uagb-block-85ac94c3 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/prembyg.dk\/wp-content\/uploads\/2023\/11\/2689D9EB-1411-4063-BE5E-55F60AD1892B-1170x536.jpg\" alt=\"\" width=\"1170\" height=\"536\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\"><strong>B\u00e6redygtig Tilretning \u2013 Forl\u00e6ng Levetiden p\u00e5 Dine Skabe<\/strong><\/h4><\/div><p class=\"uagb-ifb-desc\">I stedet for at smide gamle skabe ud kan en professionel tilpasning give dem nyt liv og reducere spild. Ved at genbruge eksisterende materialer og optimere designet bidrager du til en mere b\u00e6redygtig livsstil. Samtidig f\u00e5r du en skr\u00e6ddersyet l\u00f8sning, der b\u00e5de passer bedre til dine behov og skaber et harmonisk og langtidsholdbart udtryk i dit hjem.<br><\/p><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4bf418a0 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-93eea748\">\n<div class=\"wp-block-uagb-info-box uagb-block-97a053f8 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title-prefix\">Indhent et tilbud<\/h6><h2 class=\"uagb-ifb-title\"><strong><strong><strong>Lad os tilrette dine skabe<\/strong><\/strong><\/strong><\/h2><\/div><p class=\"uagb-ifb-desc\">Er du i tvivl om, hvorvidt dine skabe kan optimeres eller tilpasses bedre til dit hjem? Lad vores eksperter gennemg\u00e5 dem og vurdere, om en tilretning kan forbedre funktionaliteten, udnytte pladsen bedre og give et nyt, opdateret udtryk. Vi tilbyder en professionel vurdering uden forpligtelser \u2013 kontakt os i dag, og lad os finde den bedste l\u00f8sning til dine skabe!<br>Kontakt os for en uforpligtende vurdering!<br>Vi vender tilbage med et udspecificeret tilbud hurtigst muligt, dog senest efter 72 timer. Som regel kan du ringe direkte til os og f\u00e5 svar med det samme.<\/p><\/div><\/div><\/div>\n\n\n<div class='fluentform ff-default fluentform_wrapper_1 ffs_default_wrap'><form data-form_id=\"1\" id=\"fluentform_1\" class=\"frm-fluent-form fluent_form_1 ff-el-form-top ff_form_instance_1_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_1_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Indhent tilbud<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2415' \/><input type=\"hidden\" id=\"_fluentform_1_fluentformnonce\" name=\"_fluentform_1_fluentformnonce\" value=\"26442d7425\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/index.php\/wp-json\/wp\/v2\/pages\/2415\" \/><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_names_first_name_' id='label_ff_1_names_first_name_' >Fornavn<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_1_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Malene\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell '><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_names_last_name_' id='label_ff_1_names_last_name_' >Efternavn<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" id=\"ff_1_names_last_name_\" class=\"ff-el-form-control\" placeholder=\"J\u00f8rgensen\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_1\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_email' id='label_ff_1_email' aria-label=\"Email\">Email<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_1_email\" class=\"ff-el-form-control\" placeholder=\"Email Adresse\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_subject' id='label_ff_1_subject' aria-label=\"Telefonnummer\">Telefonnummer<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"subject\" class=\"ff-el-form-control\" placeholder=\"+45 \" data-name=\"subject\" id=\"ff_1_subject\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_Beskrivelse' id='label_ff_1_Beskrivelse' aria-label=\"Beskriv dit projekt\">Beskriv dit projekt<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_1_Beskrivelse\" name=\"Beskrivelse\" id=\"ff_1_Beskrivelse\" class=\"ff-el-form-control\" placeholder=\"Eksempel: Tagentreprise p\u00e5 1-plans hus i Glostrup. Ca. 135m2 tag med en h\u00e6ldning p\u00e5 30 grader. \u00d8nsker opstart inden for 3 m\u00e5neder.\" rows=\"3\" cols=\"2\" data-name=\"Beskrivelse\" ><\/textarea><\/div><\/div><div class='ff-el-group  ff-dropzone'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_image-upload_1' id='label_ff_1_image-upload_1' aria-label=\"Billeder hj\u00e6lper os med en hurtigere vurdering af omfanget (Valgfrit)\">Billeder hj\u00e6lper os med en hurtigere vurdering af omfanget (Valgfrit)<\/label><\/div><div class='ff-el-input--content'><label for='ff_1_image-upload_1' class='ff_file_upload_holder'><span class='ff_upload_btn ff-btn' tabindex='0'>V\u00e6lg filer<\/span> <input type=\"file\" name=\"image-upload\" id=\"ff_1_image-upload_1\" class=\"ff-el-form-control  ff-screen-reader-element\" accept=\"image\/*\" data-name=\"image-upload\" multiple=\"1\"  aria-invalid='false' aria-required=false><\/label><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_message' id='label_ff_1_message' aria-label=\"Hvordan og hvorn\u00e5r kontakter vi dig bedst?\">Hvordan og hvorn\u00e5r kontakter vi dig bedst?<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_1_message\" name=\"message\" id=\"ff_1_message\" class=\"ff-el-form-control\" placeholder=\"Eksempel: Jeg kontaktes bedst telefonisk efter kl. 17 p\u00e5 hverdage.\" rows=\"4\" cols=\"2\" data-name=\"message\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-center ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style\"  aria-label=\"Indhent tilbud\">Indhent tilbud<\/button><\/div><\/fieldset><\/form><div id='fluentform_1_errors' class='ff-errors-in-stack ff_form_instance_1_1 ff-form-loading_errors ff_form_instance_1_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_1_1 = {\"id\":\"1\",\"ajaxUrl\":\"https:\\\/\\\/prembyg.dk\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_1_1\",\"form_id_selector\":\"fluentform_1\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"names[last_name]\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"email\":{\"required\":{\"value\":true,\"message\":\"Dette felt skal udfyldes.\",\"global\":false,\"global_message\":\"This field is required\"},\"email\":{\"value\":true,\"message\":\"Dette felt skal indeholde en gyldig email.\",\"global\":false,\"global_message\":\"This field must contain a valid email\"}},\"subject\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"Beskrivelse\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"image-upload\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true},\"max_file_size\":{\"value\":524288000,\"_valueFrom\":\"MB\",\"message\":\"Du kan max uploade filer \\u00e1 i alt 500MB\",\"global_message\":\"Validation fails for maximum file size\",\"global\":false},\"max_file_count\":{\"value\":\"20\",\"message\":\"Du kan max uploade 20 filer.\",\"global_message\":\"Validation fails for maximum file count\",\"global\":false},\"allowed_image_types\":{\"value\":[\"jpg|jpeg\",\"png\"],\"message\":\"Du kan kun uploade PNG, JPG og .IMG\",\"global_message\":\"Allowed image types does not match\",\"global\":false}},\"message\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}}},\"debounce_time\":300};\n                            <\/script>\n            \n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-engngcdu alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-txyscjhg uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M512 80C512 98.01 497.7 114.6 473.6 128C444.5 144.1 401.2 155.5 351.3 158.9C347.7 157.2 343.9 155.5 340.1 153.9C300.6 137.4 248.2 128 192 128C183.7 128 175.6 128.2 167.5 128.6L166.4 128C142.3 114.6 128 98.01 128 80C128 35.82 213.1 0 320 0C426 0 512 35.82 512 80V80zM160.7 161.1C170.9 160.4 181.3 160 192 160C254.2 160 309.4 172.3 344.5 191.4C369.3 204.9 384 221.7 384 240C384 243.1 383.3 247.9 381.9 251.7C377.3 264.9 364.1 277 346.9 287.3C346.9 287.3 346.9 287.3 346.9 287.3C346.8 287.3 346.6 287.4 346.5 287.5L346.5 287.5C346.2 287.7 345.9 287.8 345.6 288C310.6 307.4 254.8 320 192 320C132.4 320 79.06 308.7 43.84 290.9C41.97 289.9 40.15 288.1 38.39 288C14.28 274.6 0 258 0 240C0 205.2 53.43 175.5 128 164.6C138.5 163 149.4 161.8 160.7 161.1L160.7 161.1zM391.9 186.6C420.2 182.2 446.1 175.2 468.1 166.1C484.4 159.3 499.5 150.9 512 140.6V176C512 195.3 495.5 213.1 468.2 226.9C453.5 234.3 435.8 240.5 415.8 245.3C415.9 243.6 416 241.8 416 240C416 218.1 405.4 200.1 391.9 186.6V186.6zM384 336C384 354 369.7 370.6 345.6 384C343.8 384.1 342 385.9 340.2 386.9C304.9 404.7 251.6 416 192 416C129.2 416 73.42 403.4 38.39 384C14.28 370.6 .0003 354 .0003 336V300.6C12.45 310.9 27.62 319.3 43.93 326.1C83.44 342.6 135.8 352 192 352C248.2 352 300.6 342.6 340.1 326.1C347.9 322.9 355.4 319.2 362.5 315.2C368.6 311.8 374.3 308 379.7 304C381.2 302.9 382.6 301.7 384 300.6L384 336zM416 278.1C434.1 273.1 452.5 268.6 468.1 262.1C484.4 255.3 499.5 246.9 512 236.6V272C512 282.5 507 293 497.1 302.9C480.8 319.2 452.1 332.6 415.8 341.3C415.9 339.6 416 337.8 416 336V278.1zM192 448C248.2 448 300.6 438.6 340.1 422.1C356.4 415.3 371.5 406.9 384 396.6V432C384 476.2 298 512 192 512C85.96 512 .0003 476.2 .0003 432V396.6C12.45 406.9 27.62 415.3 43.93 422.1C83.44 438.6 135.8 448 192 448z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">30-40%<\/h3><\/div><p class=\"uagb-ifb-desc\"><strong>Ved at tilrette og optimere dine skabe kan du frig\u00f8re op til 40% mere opbevaringsplads, hvilket giver en mere funktionel og ryddelig bolig. <\/strong><\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-hqpabgcv uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M464 16c-17.67 0-32 14.31-32 32v74.09C392.1 66.52 327.4 32 256 32C161.5 32 78.59 92.34 49.58 182.2c-5.438 16.81 3.797 34.88 20.61 40.28c16.89 5.5 34.88-3.812 40.3-20.59C130.9 138.5 189.4 96 256 96c50.5 0 96.26 24.55 124.4 64H336c-17.67 0-32 14.31-32 32s14.33 32 32 32h128c17.67 0 32-14.31 32-32V48C496 30.31 481.7 16 464 16zM441.8 289.6c-16.92-5.438-34.88 3.812-40.3 20.59C381.1 373.5 322.6 416 256 416c-50.5 0-96.25-24.55-124.4-64H176c17.67 0 32-14.31 32-32s-14.33-32-32-32h-128c-17.67 0-32 14.31-32 32v144c0 17.69 14.33 32 32 32s32-14.31 32-32v-74.09C119.9 445.5 184.6 480 255.1 480c94.45 0 177.4-60.34 206.4-150.2C467.9 313 458.6 294.1 441.8 289.6z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">30+ \u00e5r<\/h3><\/div><p class=\"uagb-ifb-desc\">Ved at tilpasse dine eksisterende skabe kan du forl\u00e6nge deres levetid betydeligt og sikre en l\u00f8sning, der fungerer optimalt i mange \u00e5r. <\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-24id7eza uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M64 400C64 408.8 71.16 416 80 416H480C497.7 416 512 430.3 512 448C512 465.7 497.7 480 480 480H80C35.82 480 0 444.2 0 400V64C0 46.33 14.33 32 32 32C49.67 32 64 46.33 64 64V400zM342.6 278.6C330.1 291.1 309.9 291.1 297.4 278.6L240 221.3L150.6 310.6C138.1 323.1 117.9 323.1 105.4 310.6C92.88 298.1 92.88 277.9 105.4 265.4L217.4 153.4C229.9 140.9 250.1 140.9 262.6 153.4L320 210.7L425.4 105.4C437.9 92.88 458.1 92.88 470.6 105.4C483.1 117.9 483.1 138.1 470.6 150.6L342.6 278.6z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">V\u00e6rdistigning<\/h3><\/div><p class=\"uagb-ifb-desc\">Optimering og tilpasning af dine skabe kan \u00f8ge v\u00e6rdien af din bolig ved at skabe mere funktionel og stilren opbevaringsplads. <\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-bjpcyfba uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM164.1 325.5C158.3 318.8 148.2 318.1 141.5 323.9C134.8 329.7 134.1 339.8 139.9 346.5C162.1 372.1 200.9 400 255.1 400C311.1 400 349.8 372.1 372.1 346.5C377.9 339.8 377.2 329.7 370.5 323.9C363.8 318.1 353.7 318.8 347.9 325.5C329.9 346.2 299.4 368 255.1 368C212.6 368 182 346.2 164.1 325.5H164.1zM176.4 176C158.7 176 144.4 190.3 144.4 208C144.4 225.7 158.7 240 176.4 240C194 240 208.4 225.7 208.4 208C208.4 190.3 194 176 176.4 176zM336.4 240C354 240 368.4 225.7 368.4 208C368.4 190.3 354 176 336.4 176C318.7 176 304.4 190.3 304.4 208C304.4 225.7 318.7 240 336.4 240z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Indeklima<\/h3><\/div><p class=\"uagb-ifb-desc\">Korrekt tilpassede skabe kan forbedre indeklimaet ved at reducere st\u00f8vophobning, forbedre luftcirkulationen og minimere fugtproblemer i dit hjem. <\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:46px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-4059f2c6\"><h2 class=\"uagb-heading-text\"><strong>Tilretning af skabe \u2013 F\u00e5 en skr\u00e6ddersyet l\u00f8sning uden at udskifte <\/strong>dine skabe<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-nyy5bktl alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-8o3i6bli\">\n<div class=\"wp-block-uagb-container uagb-block-nbolnovg\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-7tcyrns2 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/prembyg.dk\/wp-content\/uploads\/2025\/02\/PREMBYG-CBDK-PORTRAeTTER12-1024x683.jpg ,https:\/\/prembyg.dk\/wp-content\/uploads\/2025\/02\/PREMBYG-CBDK-PORTRAeTTER12-scaled.jpg 780w, https:\/\/prembyg.dk\/wp-content\/uploads\/2025\/02\/PREMBYG-CBDK-PORTRAeTTER12-scaled.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/prembyg.dk\/wp-content\/uploads\/2025\/02\/PREMBYG-CBDK-PORTRAeTTER12-1024x683.jpg\" alt=\"\" class=\"uag-image-2289\" width=\"510\" height=\"300\" title=\"PREMBYG CBDK PORTR\u00c6TTER12\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-65qoixr0 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><strong>Grundig R\u00e5dgivning og Pr\u00e6cis Planl\u00e6gning<\/strong><\/h3><\/div><p class=\"uagb-ifb-desc\">Vi starter med en konsultation, hvor vi gennemg\u00e5r dine \u00f8nsker og behov for tilretning af dine skabe. Uanset om du har brug for sm\u00e5 justeringer eller en st\u00f8rre tilpasning, tilbyder vi b\u00e5de hjemmebes\u00f8g og online r\u00e5dgivning for at finde den bedste l\u00f8sning. Herefter foretager vores erfarne team pr\u00e6cise m\u00e5linger og udarbejder en detaljeret plan, der sikrer, at skabene bliver tilpasset perfekt til dit rum. Vi tager h\u00f8jde for rummets dimensioner, eventuelle sk\u00e6vheder i v\u00e6gge og lofter samt dine \u00f8nsker til funktionalitet og design.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-gjyiuwjk\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-wlyadzca wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/prembyg.dk\/wp-content\/uploads\/2024\/09\/zoe-van-poetsprins-nl-x5-tEdHLqRo-unsplash-1024x683.jpg ,https:\/\/prembyg.dk\/wp-content\/uploads\/2024\/09\/zoe-van-poetsprins-nl-x5-tEdHLqRo-unsplash-scaled.jpg 780w, https:\/\/prembyg.dk\/wp-content\/uploads\/2024\/09\/zoe-van-poetsprins-nl-x5-tEdHLqRo-unsplash-scaled.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/prembyg.dk\/wp-content\/uploads\/2024\/09\/zoe-van-poetsprins-nl-x5-tEdHLqRo-unsplash-1024x683.jpg\" alt=\"\" class=\"uag-image-2103\" width=\"510\" height=\"300\" title=\"tilretning af ikeaskab\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-fcy2671s uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><strong><strong>Tilpasning, Montering og Et Perfekt Slutresultat<\/strong><\/strong><\/h3><\/div><p class=\"uagb-ifb-desc\">N\u00e5r designet er fastlagt, s\u00f8rger vores dygtige h\u00e5ndv\u00e6rkere for at tilpasse og montere dine skabe med stor pr\u00e6cision. Vi justerer l\u00e5ger, h\u00e6ngsler, skuffesystemer og hylder, s\u00e5 skabene b\u00e5de fungerer optimalt og fremst\u00e5r som nye. Med en professionel tilretning f\u00e5r du ikke blot en \u00e6stetisk opgradering, men ogs\u00e5 en holdbar l\u00f8sning, der sikrer maksimal udnyttelse af pladsen i dit hjem.<\/p><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-786e2530 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><div class=\"wp-block-uagb-faq uagb-faq__outer-wrap uagb-block-a615fd9f uagb-faq-icon-row uagb-faq-layout-accordion uagb-faq-expand-first-true uagb-faq-inactive-other-true uagb-faq__wrap uagb-buttons-layout-wrap uagb-faq-equal-height     \" data-faqtoggle=\"true\" role=\"tablist\"><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-cea10fdf \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong>Hvad er fordelene ved at tilrette eksisterende skabe frem for at k\u00f8be nye?<\/strong><\/span><\/div><div class=\"uagb-faq-content\"><p>Tilretning af skabe er en \u00f8konomisk og b\u00e6redygtig l\u00f8sning, der giver dig mulighed for at optimere pladsudnyttelsen, forbedre funktionaliteten og opgradere designet uden at skulle investere i helt nye skabe. Ved at justere l\u00e5ger, hylder og skuffesystemer kan du skabe en mere praktisk og stilren opbevaringsl\u00f8sning, der passer perfekt til dit hjem.<\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-aab1e7f8 \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong>Kan skabe tilpasses, hvis mit hjem har sk\u00e6ve v\u00e6gge eller lofter?<\/strong><\/span><\/div><div class=\"uagb-faq-content\"><p>Ja! Tilretning af skabe g\u00f8r det muligt at tilpasse eksisterende m\u00f8bler til sk\u00e6ve v\u00e6gge, skr\u00e5 lofter eller andre arkitektoniske udfordringer. Ved at justere skabets m\u00e5l og struktur kan vi sikre en perfekt pasform, s\u00e5 du f\u00e5r en mere sammenh\u00e6ngende og pladsbesparende l\u00f8sning i dit hjem.<\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-5b34470f \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong>Hvordan kan jeg optimere opbevaringspladsen i mine nuv\u00e6rende skabe?<\/strong><\/span><\/div><div class=\"uagb-faq-content\"><p>Ved at tilf\u00f8je ekstra hylder, udtr\u00e6ksskuffer eller justerbare indsatser kan vi maksimere din opbevaringsplads og g\u00f8re skabene mere funktionelle. Smarte l\u00f8sninger som skyded\u00f8re eller soft-close mekanismer kan ogs\u00e5 forbedre anvendeligheden og skabe et mere moderne udtryk.<\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-ab656ac8 \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong>Hvor lang tid tager det at tilrette skabe, og hvad koster det?<\/strong><\/span><\/div><div class=\"uagb-faq-content\"><p>Tiden og prisen afh\u00e6nger af skabets st\u00f8rrelse, kompleksiteten af tilpasningen og de \u00f8nskede \u00e6ndringer. Mindre justeringer kan ofte klares hurtigt, mens st\u00f8rre tilpasninger kr\u00e6ver mere tid. Kontakt os for en uforpligtende vurdering, s\u00e5 vi kan give dig et pr\u00e6cist estimat baseret p\u00e5 dine behov.<\/p><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tilretning af skabe &#8211; giv dine eksisterende skabe nyt liv Tilretning af skabe \u2013 F\u00e5 en skr\u00e6ddersyet l\u00f8sning uden at udskifte dine skabe<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2415","page","type-page","status-publish","hentry"],"spectra_custom_meta":{"_edit_lock":["1741352373:1"],"_has_fluentform":["a:1:{i:1;s:1:\"1\";}"],"rank_math_internal_links_processed":["1"],"rank_math_seo_score":["69"],"rank_math_focus_keyword":["Tilretning af skabe"],"om_disable_all_campaigns":[""],"_uag_custom_page_level_css":[""],"_monsterinsights_skip_tracking":[""],"_monsterinsights_sitenote_active":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":[""],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":["disabled"],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["default"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_elementor_edit_mode":[""],"_elementor_template_type":[""],"_elementor_data":[""],"_elementor_conditions":["a:0:{}"],"_edit_last":["1"],"_elementor_page_assets":["a:0:{}"],"rank_math_og_content_image":["a:2:{s:5:\"check\";s:32:\"6c845eebafe9a8c319979ad98360393a\";s:6:\"images\";a:1:{i:0;s:97:\"https:\/\/prembyg.dk\/wp-content\/uploads\/2023\/11\/CF87D5D7-8643-4684-9F6A-7E71E631257E-1-1170x536.jpg\";}}"],"_wp_page_template":["default"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:2;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:14;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:1;s:14:\"uagb\/faq-child\";i:4;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:2;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:11;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"rank_math_analytic_object_id":["20"],"_uag_css_file_name":["uag-css-2415.css"],"_uagb_last_spectra_edit":["1776774302"],"_uag_page_assets":["a:9:{s:3:\"css\";s:200891:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.wp-block-uagb-faq{width:100%}.wp-block-uagb-faq.uagb-faq-layout-accordion .uagb-faq-child__outer-wrap .uagb-faq-questions-button{cursor:pointer}.wp-block-uagb-faq .uagb-faq-content{margin-bottom:0}.wp-block-uagb-faq .uagb-faq-content p{margin:auto}.uagb-faq-layout-grid.uagb-faq-equal-height.uagb-faq__wrap .uagb-faq-child__outer-wrap,.uagb-faq-layout-grid.uagb-faq-equal-height.uagb-faq__wrap .uagb-faq-item{height:100%}body[class*=astra] .uagb-faq-questions{line-height:normal}.uagb-faq-item{overflow:hidden}.wp-block-uagb-faq-child .uagb-faq-questions-button{display:flex;align-items:center}.wp-block-uagb-faq-child .uagb-faq-questions-button .uagb-faq-icon-wrap{display:flex;align-items:center}.wp-block-uagb-faq-child .uagb-faq-questions-button .uagb-question{width:100%;margin-top:0;margin-bottom:0}.wp-block-uagb-faq-child .uagb-icon svg,.wp-block-uagb-faq-child .uagb-icon-active svg{width:15px;height:15px;font-size:15px}.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon{display:none;width:0;padding:0;height:0;margin:0}.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon,.wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:flex;width:auto;height:auto}.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item .uagb-icon,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item .uagb-icon,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:none}.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item span.uagb-icon-active.uagb-faq-icon-wrap,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap.uagb-faq-item.uagb-faq-item-active .uagb-icon-active,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item span.uagb-icon-active.uagb-faq-icon-wrap,.uagb-faq-layout-grid .uagb-faq-child__outer-wrap .uagb-faq-item.uagb-faq-item-active .uagb-icon-active{display:none}.wp-block-uagb-container.uagb-block-b5d35cd4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b5d35cd4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b5d35cd4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b5d35cd4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b5d35cd4 .uagb-container__video-wrap video{opacity: 0.35;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b5d35cd4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b5d35cd4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b5d35cd4{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 130px;padding-bottom: 120px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 15px;border-bottom-right-radius: 15px;border-color: inherit;background-repeat: no-repeat;background-position: 43% 60%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/prembyg.dk\/wp-content\/uploads\/2023\/11\/137FE54F-5C0D-41E5-878C-D2A98574858F-scaled.jpg);background-clip: padding-box;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b5d35cd4::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 15px;border-bottom-right-radius: 15px;border-color: inherit;background: rgba(18,18,18,0.39);opacity: 0.65;}.wp-block-uagb-advanced-heading.uagb-block-90747899.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-90747899.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-90747899.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-90747899.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-90747899.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-90747899.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-47f641d6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-47f641d6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-47f641d6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-47f641d6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-47f641d6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-47f641d6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-47f641d6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 30px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-47f641d6{box-shadow: 0px 0px   #00000070 ;padding-top: 100px;padding-bottom: 60px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 30px;column-gap: 20px;}.uagb-block-25ac16a2 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-25ac16a2 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-25ac16a2 .uagb-ifb-icon svg{fill: #333;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-25ac16a2 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-25ac16a2 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-25ac16a2 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-25ac16a2 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-25ac16a2 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-25ac16a2 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-25ac16a2 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-1);margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-25ac16a2.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-25ac16a2.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-25ac16a2 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-25ac16a2 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-25ac16a2 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-25ac16a2 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-25ac16a2 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-25ac16a2.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-25ac16a2.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-25ac16a2 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-25ac16a2.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-25ac16a2.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-25ac16a2.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-ed2c2e06 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ed2c2e06 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ed2c2e06 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ed2c2e06 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ed2c2e06 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ed2c2e06{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ed2c2e06 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: space-between;flex-wrap: wrap;row-gap: 40px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ed2c2e06{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 40px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5b23f554 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5b23f554 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5b23f554 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5b23f554 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5b23f554 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b23f554{max-width: 31%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b23f554 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5b23f554{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-style: solid;border-color: rgba(0,0,0,0.06);flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-4d1b1cd4 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4d1b1cd4 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-4d1b1cd4 .uagb-ifb-icon svg{fill: #333;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4d1b1cd4 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4d1b1cd4 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4d1b1cd4 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4d1b1cd4 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4d1b1cd4 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4d1b1cd4 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4d1b1cd4 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-4d1b1cd4.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-4d1b1cd4.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-4d1b1cd4 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-4d1b1cd4 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-4d1b1cd4 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-4d1b1cd4 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4d1b1cd4 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-4d1b1cd4.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4d1b1cd4 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-fe0a0c96 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fe0a0c96 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fe0a0c96 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fe0a0c96 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fe0a0c96 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fe0a0c96{max-width: 31%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fe0a0c96 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fe0a0c96{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-style: solid;border-color: rgba(0,0,0,0.06);flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-01f03b24 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-01f03b24 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-01f03b24 .uagb-ifb-icon svg{fill: #333;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-01f03b24 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-01f03b24 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-01f03b24 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-01f03b24 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-01f03b24 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-01f03b24 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-01f03b24 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-01f03b24.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-01f03b24.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-01f03b24 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-01f03b24 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-01f03b24 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-01f03b24 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-01f03b24 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-01f03b24.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-01f03b24.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-01f03b24 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-fa91d8ee .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fa91d8ee .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fa91d8ee .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fa91d8ee .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fa91d8ee .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fa91d8ee{max-width: 31%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fa91d8ee > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fa91d8ee{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-style: solid;border-color: rgba(0,0,0,0.06);flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-85ac94c3 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-85ac94c3 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-85ac94c3 .uagb-ifb-icon svg{fill: #333;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-85ac94c3 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-85ac94c3 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-85ac94c3 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-85ac94c3 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-85ac94c3 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-85ac94c3.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-85ac94c3.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-85ac94c3 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-85ac94c3 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-85ac94c3 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-85ac94c3 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-85ac94c3 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-85ac94c3.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-85ac94c3.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-85ac94c3 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-4bf418a0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4bf418a0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4bf418a0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4bf418a0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4bf418a0 .uagb-container__video-wrap video{opacity: 0;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4bf418a0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4bf418a0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4bf418a0{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 200px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 100% 10%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/prembyg.dk\/wp-content\/uploads\/2025\/02\/PREMBYG-CBDK01-scaled.jpg);background-clip: padding-box;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4bf418a0::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background-image: linear-gradient(180deg,rgb(255,255,255) 0%,rgba(155,81,224,0) 100%);opacity: 1;}.wp-block-uagb-container.uagb-block-93eea748 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-93eea748 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-93eea748 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-93eea748 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-93eea748 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-93eea748{max-width: 750px;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-93eea748 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-93eea748{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 20px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 15px;border-top-right-radius: 15px;border-bottom-left-radius: 15px;border-bottom-right-radius: 15px;border-color: inherit;background-color: var(--ast-global-color-5);;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-97a053f8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-97a053f8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-97a053f8 .uagb-ifb-icon svg{fill: #333;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-97a053f8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-97a053f8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-97a053f8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-97a053f8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-97a053f8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-97a053f8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-97a053f8.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-97a053f8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-1);margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-97a053f8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 15px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-97a053f8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-97a053f8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-97a053f8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-97a053f8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-97a053f8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-97a053f8 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-97a053f8.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-97a053f8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-97a053f8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-97a053f8 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-97a053f8.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-97a053f8.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-97a053f8.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-engngcdu .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-engngcdu .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-engngcdu .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-engngcdu .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-engngcdu .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-engngcdu{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-engngcdu > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-engngcdu{box-shadow: 0px 4px 8px -2px rgba(0,0,0,0.12) ;padding-top: 48px;padding-bottom: 48px;padding-left: 48px;padding-right: 48px;margin-top:  !important;margin-bottom:  !important;overflow: hidden;order: initial;border-top-width: 0px;border-left-width: 0px;border-right-width: 0px;border-bottom-width: 0px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 15px;border-bottom-right-radius: 15px;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-0);;row-gap: 0px;column-gap: 24px;}.uagb-block-txyscjhg .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-txyscjhg .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;color: var(--ast-global-color-0);}.uagb-block-txyscjhg .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-txyscjhg .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-txyscjhg .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 24px;height: 24px;line-height: 24px;padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-txyscjhg .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-txyscjhg .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-txyscjhg .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-txyscjhg .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-txyscjhg .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-txyscjhg.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 12px;margin-top: 0px;margin-left: 10px;margin-right: 0px;}.uagb-block-txyscjhg.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 10px;margin-right: 0px;}.uagb-block-txyscjhg .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-txyscjhg .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-txyscjhg .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-txyscjhg .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-txyscjhg .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-4);border-radius: 50%;}.uagb-block-txyscjhg .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-4);}.uagb-block-txyscjhg .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-txyscjhg.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-txyscjhg .uagb-iconbox-icon-wrap{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-hqpabgcv .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-hqpabgcv .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;color: var(--ast-global-color-0);}.uagb-block-hqpabgcv .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-hqpabgcv .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-hqpabgcv .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 24px;height: 24px;line-height: 24px;padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-hqpabgcv .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-hqpabgcv .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-hqpabgcv .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-hqpabgcv .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-hqpabgcv .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-hqpabgcv.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 12px;margin-top: 0px;margin-left: 10px;margin-right: 0px;}.uagb-block-hqpabgcv.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 10px;margin-right: 0px;}.uagb-block-hqpabgcv .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-hqpabgcv .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-hqpabgcv .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-hqpabgcv .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-hqpabgcv .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-4);border-radius: 50%;}.uagb-block-hqpabgcv .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-4);}.uagb-block-hqpabgcv .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-hqpabgcv .uagb-iconbox-icon-wrap{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-24id7eza .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-24id7eza .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;color: var(--ast-global-color-0);}.uagb-block-24id7eza .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-24id7eza .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-24id7eza .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 24px;height: 24px;line-height: 24px;padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-24id7eza .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-24id7eza .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-24id7eza .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-24id7eza .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-24id7eza.uagb-infobox__content-wrap img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-24id7eza .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-24id7eza.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 12px;margin-top: 0px;margin-left: 10px;margin-right: 0px;}.uagb-block-24id7eza.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 10px;margin-right: 0px;}.uagb-block-24id7eza .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-24id7eza .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-24id7eza .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-24id7eza .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-24id7eza .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-5);border-radius: 50%;}.uagb-block-24id7eza .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-5);}.uagb-block-24id7eza .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-24id7eza.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-24id7eza.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-24id7eza .uagb-iconbox-icon-wrap{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-bjpcyfba .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-bjpcyfba .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;color: var(--ast-global-color-0);}.uagb-block-bjpcyfba .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-bjpcyfba .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-bjpcyfba .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 24px;height: 24px;line-height: 24px;padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-bjpcyfba .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-bjpcyfba .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-bjpcyfba .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-bjpcyfba .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-bjpcyfba .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-bjpcyfba.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 12px;margin-top: 0px;margin-left: 10px;margin-right: 0px;}.uagb-block-bjpcyfba.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 10px;margin-right: 0px;}.uagb-block-bjpcyfba .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-bjpcyfba .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-bjpcyfba .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-bjpcyfba .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bjpcyfba .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-5);border-radius: 50%;}.uagb-block-bjpcyfba .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-5);}.uagb-block-bjpcyfba .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bjpcyfba .uagb-iconbox-icon-wrap{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-4059f2c6.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-4059f2c6.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-4059f2c6.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4059f2c6.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4059f2c6.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-nyy5bktl .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-nyy5bktl .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-nyy5bktl .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-nyy5bktl .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-nyy5bktl .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-nyy5bktl{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-nyy5bktl > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 48px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-nyy5bktl{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 50px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-style: none;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 48px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-8o3i6bli .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8o3i6bli .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8o3i6bli .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8o3i6bli .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8o3i6bli .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8o3i6bli{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8o3i6bli > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8o3i6bli.uagb-layout-grid{row-gap: 48px;column-gap: 48px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-8o3i6bli{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: inherit;}.wp-block-uagb-container.uagb-block-nbolnovg .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-nbolnovg .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-nbolnovg .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-nbolnovg .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-nbolnovg .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-nbolnovg{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-nbolnovg > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-nbolnovg{box-shadow: 0px 0px   #00000070 ;padding-top: 32px;padding-bottom: 32px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: hidden;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.uagb-block-7tcyrns2.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-7tcyrns2 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-7tcyrns2.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-7tcyrns2.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-7tcyrns2.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-7tcyrns2.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-7tcyrns2.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-7tcyrns2.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-7tcyrns2.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-7tcyrns2.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-7tcyrns2.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-7tcyrns2.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-7tcyrns2.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 510px;height: 300px;}.uagb-block-7tcyrns2.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-7tcyrns2.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-7tcyrns2.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-7tcyrns2.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-65qoixr0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-65qoixr0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-65qoixr0 .uagb-ifb-icon svg{fill: #333;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-65qoixr0 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-65qoixr0 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-65qoixr0 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-65qoixr0 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-65qoixr0 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-65qoixr0 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-65qoixr0 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-65qoixr0.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-65qoixr0.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 28px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-65qoixr0 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-65qoixr0 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-65qoixr0 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-65qoixr0 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-65qoixr0 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-65qoixr0.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-65qoixr0 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-65qoixr0.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-65qoixr0.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-65qoixr0.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-gjyiuwjk .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-gjyiuwjk .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-gjyiuwjk .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-gjyiuwjk .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-gjyiuwjk .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-gjyiuwjk{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-gjyiuwjk > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-gjyiuwjk{box-shadow: 0px 0px   #00000070 ;padding-top: 32px;padding-bottom: 32px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: hidden;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.uagb-block-wlyadzca.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-wlyadzca .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-wlyadzca.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-wlyadzca.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-wlyadzca.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-wlyadzca.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-wlyadzca.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-wlyadzca.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-wlyadzca.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-wlyadzca.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-wlyadzca.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-wlyadzca.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-wlyadzca.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 510px;height: 300px;}.uagb-block-wlyadzca.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-wlyadzca.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-wlyadzca.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-wlyadzca.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-fcy2671s .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fcy2671s .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-fcy2671s .uagb-ifb-icon svg{fill: #333;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fcy2671s .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fcy2671s .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fcy2671s .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fcy2671s .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fcy2671s .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fcy2671s .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fcy2671s .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-fcy2671s.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fcy2671s.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 28px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fcy2671s .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-fcy2671s .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-fcy2671s .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-fcy2671s .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fcy2671s .uagb-infobox__content-wrap{text-align: left;}.uagb-block-fcy2671s.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-fcy2671s .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fcy2671s.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fcy2671s.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-fcy2671s.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-786e2530 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-786e2530 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-786e2530 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-786e2530 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-786e2530 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-786e2530{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-786e2530 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 48px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-786e2530{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 48px;column-gap: 0px;}.uagb-block-a615fd9f .uagb-icon svg{width: 12px;height: 12px;font-size: 12px;}.uagb-block-a615fd9f .uagb-icon-active svg{width: 12px;height: 12px;font-size: 12px;}.uagb-block-a615fd9f .uagb-faq-child__outer-wrap{margin-bottom: 10px;}.uagb-block-a615fd9f .uagb-faq-item{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 2px;border-top-right-radius: 2px;border-bottom-left-radius: 2px;border-bottom-right-radius: 2px;border-color: #D2D2D2;border-style: solid;}.uagb-block-a615fd9f .uagb-faq-questions-button{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-a615fd9f .uagb-faq-content{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-a615fd9f .uagb-faq-content span{margin-top: 10px;margin-bottom: 10px;margin-right: 10px;margin-left: 10px;}.uagb-block-a615fd9f.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 10px;}.uagb-block-a615fd9f.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 10px;}.uagb-block-a615fd9f .uagb-faq-item .uagb-faq-questions-button.uagb-faq-questions{flex-direction: row;}.uagb-block-a615fd9f .wp-block-uagb-faq-child.uagb-faq-child__outer-wrap .uagb-faq-content {display: none;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-b5d35cd4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b5d35cd4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b5d35cd4{padding-top: 150px;padding-bottom: 150px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/prembyg.dk\/wp-content\/uploads\/2023\/11\/137FE54F-5C0D-41E5-878C-D2A98574858F-scaled.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-b5d35cd4::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: rgba(18,18,18,0.39);opacity: 0.65;}.wp-block-uagb-advanced-heading.uagb-block-90747899.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-47f641d6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-47f641d6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-47f641d6{padding-top: 50px;padding-bottom: 50px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;row-gap: 0px;column-gap: 0px;}.uagb-block-25ac16a2 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-25ac16a2.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-25ac16a2 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-25ac16a2 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-25ac16a2 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-25ac16a2 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25ac16a2 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25ac16a2.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-25ac16a2.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-25ac16a2.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ed2c2e06{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ed2c2e06 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;justify-content: space-between;flex-wrap: wrap;row-gap: 30px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-ed2c2e06{padding-top: 30px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 30px;column-gap: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b23f554{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b23f554 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-5b23f554{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: solid;border-color: rgba(0,0,0,0.06);row-gap: 0px;column-gap: 0px;}.uagb-block-4d1b1cd4.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-4d1b1cd4 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-4d1b1cd4 .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-4d1b1cd4 .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4d1b1cd4 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4d1b1cd4 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-4d1b1cd4 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-4d1b1cd4 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4d1b1cd4 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4 .uagb-infobox-icon-right:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4 .uagb-infobox-icon-left:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fe0a0c96{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fe0a0c96 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-fe0a0c96{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: solid;border-color: rgba(0,0,0,0.06);row-gap: 0px;column-gap: 0px;}.uagb-block-01f03b24.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 20px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-01f03b24.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-01f03b24 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-01f03b24 .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-01f03b24 .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-01f03b24 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-01f03b24 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-01f03b24 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-01f03b24 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-01f03b24 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-01f03b24.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24 .uagb-infobox-icon-right:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24 .uagb-infobox-icon-left:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fa91d8ee{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fa91d8ee > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-fa91d8ee{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: solid;border-color: rgba(0,0,0,0.06);row-gap: 0px;column-gap: 0px;}.uagb-block-85ac94c3.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 20px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-85ac94c3.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3 .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3 .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-85ac94c3 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-85ac94c3 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-85ac94c3 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-85ac94c3 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3 .uagb-infobox-icon-right:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3 .uagb-infobox-icon-left:hover > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4bf418a0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4bf418a0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4bf418a0{padding-top: 0px;padding-bottom: 200px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/prembyg.dk\/wp-content\/uploads\/2025\/02\/PREMBYG-CBDK01-scaled.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-4bf418a0::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background-image: linear-gradient(180deg,rgb(255,255,255) 0%,rgba(155,81,224,0) 100%);opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-93eea748{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-93eea748 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;flex-wrap: nowrap;row-gap: 30px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-93eea748{padding-top: 0px;padding-bottom: 30px;padding-left: 50px;padding-right: 50px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;flex-direction: column;flex-wrap: nowrap;row-gap: 30px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-93eea748.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-93eea748.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-97a053f8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-97a053f8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 15px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-97a053f8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-97a053f8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-97a053f8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-97a053f8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-97a053f8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-97a053f8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-97a053f8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-97a053f8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-engngcdu{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-engngcdu > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;column-gap: 30px;}.wp-block-uagb-container.uagb-block-engngcdu{padding-top: 20px;padding-bottom: 20px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-0);;column-gap: 30px;}.wp-block-uagb-container.uagb-block-engngcdu.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-engngcdu.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-txyscjhg.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-txyscjhg.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-txyscjhg .uagb-ifb-content > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-txyscjhg .uagb-infobox-icon-right:hover > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-txyscjhg .uagb-infobox-icon-left:hover > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-txyscjhg .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-txyscjhg .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-txyscjhg .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-txyscjhg .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-txyscjhg .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-txyscjhg .uagb-infobox-margin-wrapper{display: flex;}.uagb-block-txyscjhg.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-txyscjhg .uagb-ifb-content > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-txyscjhg .uagb-infobox-icon-right:hover > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-txyscjhg .uagb-infobox-icon-left:hover > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-hqpabgcv.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-hqpabgcv.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-hqpabgcv .uagb-ifb-content > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-hqpabgcv .uagb-infobox-icon-right:hover > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-hqpabgcv .uagb-infobox-icon-left:hover > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-hqpabgcv .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-hqpabgcv .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-hqpabgcv .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-hqpabgcv .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-hqpabgcv .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-hqpabgcv .uagb-infobox-margin-wrapper{display: flex;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-hqpabgcv .uagb-ifb-content > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-hqpabgcv .uagb-infobox-icon-right:hover > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-hqpabgcv .uagb-infobox-icon-left:hover > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-24id7eza.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-24id7eza.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-24id7eza.uagb-infobox__content-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-24id7eza .uagb-ifb-content > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-24id7eza .uagb-infobox-icon-right:hover > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-24id7eza .uagb-infobox-icon-left:hover > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-24id7eza.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-24id7eza .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-24id7eza .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-24id7eza .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-24id7eza .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-24id7eza .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-24id7eza .uagb-infobox-margin-wrapper{display: flex;}.uagb-block-24id7eza.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-24id7eza.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-24id7eza .uagb-ifb-content > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-24id7eza .uagb-infobox-icon-right:hover > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-24id7eza .uagb-infobox-icon-left:hover > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-bjpcyfba.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-bjpcyfba.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-bjpcyfba .uagb-ifb-content > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-bjpcyfba .uagb-infobox-icon-right:hover > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-bjpcyfba .uagb-infobox-icon-left:hover > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bjpcyfba .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-bjpcyfba .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-bjpcyfba .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-bjpcyfba .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-bjpcyfba .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-bjpcyfba .uagb-infobox-margin-wrapper{display: flex;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-bjpcyfba .uagb-ifb-content > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-bjpcyfba .uagb-infobox-icon-right:hover > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-bjpcyfba .uagb-infobox-icon-left:hover > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-nyy5bktl{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-nyy5bktl > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-nyy5bktl{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: none;background-color: var(--ast-global-color-5);;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8o3i6bli{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8o3i6bli > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8o3i6bli.uagb-layout-grid{row-gap: 40px;column-gap: 40px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-8o3i6bli{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-nbolnovg{max-width: 47%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-nbolnovg > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-nbolnovg{padding-top: 16px;padding-bottom: 16px;padding-left: 16px;padding-right: 16px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;row-gap: 24px;column-gap: 0px;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-7tcyrns2.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 300px;height: 200px;}.uagb-block-65qoixr0.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-65qoixr0.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-65qoixr0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-65qoixr0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-65qoixr0 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-65qoixr0 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-65qoixr0 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-gjyiuwjk{max-width: 47%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-gjyiuwjk > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-gjyiuwjk{padding-top: 16px;padding-bottom: 16px;padding-left: 16px;padding-right: 16px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;row-gap: 24px;column-gap: 0px;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-wlyadzca.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 300px;height: 200px;}.uagb-block-fcy2671s.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fcy2671s.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fcy2671s .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fcy2671s .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-fcy2671s .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-fcy2671s .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fcy2671s .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-786e2530{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-786e2530 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-786e2530{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;row-gap: 40px;column-gap: 0px;}.uagb-block-a615fd9f.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 10px;}.uagb-block-a615fd9f.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 10px;}.uagb-block-a615fd9f .uagb-faq-questions-button{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-a615fd9f .uagb-faq-content{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-a615fd9f .uagb-faq-content span{margin-top: 10px;margin-bottom: 10px;margin-right: 10px;margin-left: 10px;}.uagb-block-a615fd9f .uagb-faq-item{border-style: solid;border-color: #D2D2D2;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-b5d35cd4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b5d35cd4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b5d35cd4{padding-top: 150px;padding-bottom: 150px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;background-image: url(https:\/\/prembyg.dk\/wp-content\/uploads\/2023\/11\/137FE54F-5C0D-41E5-878C-D2A98574858F-scaled.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-b5d35cd4::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: rgba(18,18,18,0.39);opacity: 0.65;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-47f641d6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-47f641d6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-47f641d6{padding-top: 50px;padding-bottom: 50px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-5);;}.uagb-block-25ac16a2 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-25ac16a2.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-25ac16a2 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25ac16a2 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-25ac16a2 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-25ac16a2 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-25ac16a2 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-25ac16a2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ed2c2e06{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ed2c2e06 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ed2c2e06{padding-top: 30px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b23f554{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b23f554 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5b23f554{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: solid;border-color: rgba(0,0,0,0.06);flex-wrap: wrap;}.uagb-block-4d1b1cd4.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-4d1b1cd4.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4d1b1cd4 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4d1b1cd4 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4d1b1cd4 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4d1b1cd4 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4d1b1cd4 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-4d1b1cd4 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4d1b1cd4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fe0a0c96{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fe0a0c96 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-fe0a0c96{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: solid;border-color: rgba(0,0,0,0.06);flex-wrap: wrap;}.uagb-block-01f03b24.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-01f03b24.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-01f03b24 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-01f03b24 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-01f03b24 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-01f03b24 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-01f03b24 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-01f03b24.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-01f03b24.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fa91d8ee{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fa91d8ee > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-fa91d8ee{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: solid;border-color: rgba(0,0,0,0.06);flex-wrap: wrap;}.uagb-block-85ac94c3.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-85ac94c3.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-85ac94c3 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-85ac94c3 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-85ac94c3 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85ac94c3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4bf418a0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4bf418a0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4bf418a0{padding-top: 0px;padding-bottom: 200px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/prembyg.dk\/wp-content\/uploads\/2025\/02\/PREMBYG-CBDK01-scaled.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-4bf418a0::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background-image: linear-gradient(180deg,rgb(255,255,255) 0%,rgba(155,81,224,0) 100%);opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-93eea748{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-93eea748 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;flex-wrap: nowrap;row-gap: 30px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-93eea748{padding-top: 30px;padding-bottom: 30px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 30px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-5);;flex-direction: column;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-93eea748.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-93eea748.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-97a053f8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-97a053f8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-97a053f8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-97a053f8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-97a053f8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-97a053f8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-97a053f8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-97a053f8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-97a053f8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-97a053f8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-97a053f8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-engngcdu{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-engngcdu > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-engngcdu{padding-top: 32px;padding-bottom: 32px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-0);;}.uagb-block-txyscjhg.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-txyscjhg.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;}.uagb-block-txyscjhg .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-txyscjhg .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-txyscjhg .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-txyscjhg .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-txyscjhg .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-txyscjhg .uagb-infobox-margin-wrapper{display: flex;}.uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-txyscjhg.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-hqpabgcv.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-hqpabgcv.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;}.uagb-block-hqpabgcv .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-hqpabgcv .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-hqpabgcv .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-hqpabgcv .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-hqpabgcv .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-hqpabgcv .uagb-infobox-margin-wrapper{display: flex;}.uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-hqpabgcv.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-24id7eza.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-24id7eza.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;}.uagb-block-24id7eza .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-24id7eza .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-24id7eza .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-24id7eza .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-24id7eza .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-24id7eza .uagb-infobox-margin-wrapper{display: flex;}.uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-24id7eza.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-bjpcyfba.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-bjpcyfba.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;}.uagb-block-bjpcyfba .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-bjpcyfba .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bjpcyfba .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-bjpcyfba .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-bjpcyfba .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-bjpcyfba .uagb-infobox-margin-wrapper{display: flex;}.uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bjpcyfba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-nyy5bktl{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-nyy5bktl > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-nyy5bktl{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;column-gap: 0px;order: initial;border-style: none;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8o3i6bli{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8o3i6bli > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8o3i6bli.uagb-layout-grid{row-gap: 24px;column-gap: 0px;grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-8o3i6bli{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-nbolnovg{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-nbolnovg > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-nbolnovg{padding-top: 16px;padding-bottom: 16px;padding-left: 16px;padding-right: 16px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-7tcyrns2.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 200px;}.uagb-block-65qoixr0.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-65qoixr0.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-65qoixr0 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-65qoixr0 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-65qoixr0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-65qoixr0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-65qoixr0 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-65qoixr0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-gjyiuwjk{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-gjyiuwjk > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-gjyiuwjk{padding-top: 16px;padding-bottom: 16px;padding-left: 16px;padding-right: 16px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-wlyadzca.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 200px;}.uagb-block-fcy2671s.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fcy2671s.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-fcy2671s .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fcy2671s .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fcy2671s .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fcy2671s .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-fcy2671s .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-fcy2671s.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-786e2530{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-786e2530 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-786e2530{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-5);;}.uagb-block-a615fd9f.uagb-faq-icon-row .uagb-faq-item .uagb-faq-icon-wrap{margin-right: 10px;}.uagb-block-a615fd9f .uagb-faq-item{border-style: solid;border-color: #D2D2D2;}.uagb-block-a615fd9f.uagb-faq-icon-row-reverse .uagb-faq-item .uagb-faq-icon-wrap{margin-left: 10px;}.uagb-block-a615fd9f .uagb-faq-questions-button{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-a615fd9f .uagb-faq-content{padding-top: 10px;padding-bottom: 10px;padding-right: 10px;padding-left: 10px;}.uagb-block-a615fd9f .uagb-faq-content span{margin-top: 10px;margin-bottom: 10px;margin-right: 10px;margin-left: 10px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.uagb-block-3ab76b12.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3ab76b12.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-3ab76b12.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3ab76b12.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-3ab76b12.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-3ab76b12.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-3ab76b12.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-3ab76b12.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-3ab76b12.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-3ab76b12.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-3ab76b12.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-3ab76b12.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-3ab76b12.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-3ab76b12.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3ab76b12.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-3ab76b12.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-3ab76b12.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-a2235db5.wp-block-uagb-image{text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-a2235db5 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-a2235db5.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a2235db5.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-a2235db5.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a2235db5.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-a2235db5.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-a2235db5.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-a2235db5.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-a2235db5.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-a2235db5.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-a2235db5.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-a2235db5.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 226px;height: auto;}.uagb-block-a2235db5.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-a2235db5.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-a2235db5.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a2235db5.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-a2235db5.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 226px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-a2235db5.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 226px;height: auto;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:20:{i:0;s:14:\"uagb\/container\";i:1;s:21:\"uagb\/advanced-heading\";i:3;s:13:\"uagb\/info-box\";i:4;s:14:\"core\/shortcode\";i:5;s:11:\"core\/spacer\";i:9;s:10:\"uagb\/image\";i:11;s:8:\"uagb\/faq\";i:12;s:14:\"uagb\/faq-child\";i:13;s:14:\"core\/paragraph\";i:14;s:11:\"core\/search\";i:15;s:10:\"core\/group\";i:16;s:12:\"core\/heading\";i:17;s:17:\"core\/latest-posts\";i:18;s:20:\"core\/latest-comments\";i:19;s:13:\"core\/archives\";i:20;s:15:\"core\/categories\";i:21;s:12:\"core\/gallery\";i:22;s:10:\"core\/image\";i:23;s:9:\"core\/list\";i:24;s:14:\"core\/list-item\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778440876\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:1;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"prembyg.dk","author_link":"https:\/\/prembyg.dk\/author\/prembyg-dk\/"},"uagb_comment_info":0,"uagb_excerpt":"Tilretning af skabe &#8211; giv dine eksisterende skabe nyt liv Tilretning af skabe \u2013 F\u00e5 en skr\u00e6ddersyet l\u00f8sning uden at udskifte dine skabe","_links":{"self":[{"href":"https:\/\/prembyg.dk\/index.php\/wp-json\/wp\/v2\/pages\/2415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prembyg.dk\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/prembyg.dk\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/prembyg.dk\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prembyg.dk\/index.php\/wp-json\/wp\/v2\/comments?post=2415"}],"version-history":[{"count":11,"href":"https:\/\/prembyg.dk\/index.php\/wp-json\/wp\/v2\/pages\/2415\/revisions"}],"predecessor-version":[{"id":2675,"href":"https:\/\/prembyg.dk\/index.php\/wp-json\/wp\/v2\/pages\/2415\/revisions\/2675"}],"wp:attachment":[{"href":"https:\/\/prembyg.dk\/index.php\/wp-json\/wp\/v2\/media?parent=2415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}